{"id":1592,"date":"2025-11-10T10:57:31","date_gmt":"2025-11-10T13:57:31","guid":{"rendered":"https:\/\/lucasmalaspina.com\/?p=1592"},"modified":"2025-11-10T11:27:02","modified_gmt":"2025-11-10T14:27:02","slug":"milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine","status":"publish","type":"post","link":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/","title":{"rendered":"\u00c9lections de mi-mandat 2025 : ce qui s&rsquo;est pass\u00e9 en Argentine"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si pour des raisons professionnelles et\/ou personnelles, vous essayez de comprendre ce qui s&rsquo;est pass\u00e9 lors des \u00e9lections l\u00e9gislatives et parlementaires du dimanche 26 octobre, ceci peut vous aider.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Si vous avez des commentaires, des questions ou des critiques, ils sont les bienvenus et vous pouvez les laisser ci-dessous, je vous r\u00e9pondrai tr\u00e8s certainement.<\/em><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Certains d\u00e9lirants en viennent \u00e0 croire qu&rsquo;il y a eu fraude<\/strong>, car selon eux, il n&rsquo;est pas possible qu&rsquo;un \u00e9cart de 13 points ait \u00e9t\u00e9 combl\u00e9 lors des \u00e9lections dans la province de Buenos Aires. Ce sont maintenant des d\u00e9lirants anti-Milei, et lorsque les r\u00e9sultats ont \u00e9t\u00e9 d\u00e9favorables \u00e0 Milei, les d\u00e9lirants pro-Milei sont apparus, qui ont soutenu exactement la m\u00eame chose.&nbsp;<strong>Le syst\u00e8me \u00e9lectoral argentin est fiable : personne de s\u00e9rieux ne le conteste.<\/strong> Rappelons-nous que lors des \u00e9lections pr\u00e9sidentielles g\u00e9n\u00e9rales de 2023, Sergio Massa (p\u00e9roniste-kirchn\u00e9riste) est arriv\u00e9 en t\u00eate avec 37 % des voix et n&rsquo;\u00e9tait qu&rsquo;\u00e0 3 points de gouverner l&rsquo;Argentine&#8230; dans un pays o\u00f9 l&rsquo;inflation annuelle \u00e9tait de 143 %. \u00c0 l&rsquo;\u00e9poque, les anti-p\u00e9ronistes affirmaient que le p\u00e9ronisme avait commis une fraude.&nbsp;<strong>Il n&rsquo;y a pas eu de fraude en 2023, il n&rsquo;y a pas eu de fraude aujourd&rsquo;hui, il n&rsquo;y a pas eu de fraude en septembre.<\/strong><\/li>\n\n\n\n<li>La Libertad Avanza ne d\u00e9tient pas l&rsquo;ensemble du pouvoir public : <strong>C&rsquo;EST SEULEMENT le seul parti politique v\u00e9ritablement national en Argentine.&nbsp;<\/strong>C&rsquo;est le m\u00e9rite de l&rsquo;image personnelle du pr\u00e9sident Milei : c&rsquo;est principalement gr\u00e2ce \u00e0 son image personnelle d&rsquo;envergure nationale qu&rsquo;il a un parti. Ce parti n&rsquo;a pas \u00e9t\u00e9 cr\u00e9\u00e9 selon les meilleures possibilit\u00e9s offertes par la technique politique moderne ; il en est tr\u00e8s loin. Mais entre 2023 et 2024, il a \u00e9t\u00e9 constitu\u00e9 dans toutes les provinces, et pour l&rsquo;instant, cela lui a suffi.<\/li>\n\n\n\n<li><strong>Le p\u00e9ronisme-kirchn\u00e9risme (Fuerza Patria) n&rsquo;est PAS un parti politique national aujourd&rsquo;hui, c&rsquo;est une coop\u00e9rative \u00e9lectorale post-\u00ab albertiste \u00bb (c&rsquo;est-\u00e0-dire qui rassemble les ruines du gouvernement d&rsquo;Alberto Fern\u00e1ndez).&nbsp;<\/strong>On le savait AVANT les \u00e9lections d&rsquo;hier et cela s&rsquo;est \u00e0 nouveau confirm\u00e9. Pourquoi ? Parce que le p\u00e9ronisme-kirchn\u00e9risme (ni avec l&rsquo;ancienne pr\u00e9sidente Cristina Fern\u00e1ndez de Kirchner, ni avec le gouverneur Axel Kicillof) ne parvient pas aujourd&rsquo;hui \u00e0 avoir des partis importants ou comp\u00e9titifs dans toutes les provinces. Pas m\u00eame, du moins, dans toutes les provinces importantes. Dans la deuxi\u00e8me province la plus importante du pays, C\u00f3rdoba, le p\u00e9ronisme-kirchn\u00e9risme est pass\u00e9 de 10 % (lors des \u00e9lections l\u00e9gislatives de 2021) \u00e0 5 % cette ann\u00e9e. C\u00f3rdoba repr\u00e9sente pr\u00e8s de 9 % de l&rsquo;\u00e9lectorat argentin : il existe l\u00e0-bas une variante provinciale du p\u00e9ronisme (appel\u00e9e \u00ab cordob\u00e9siste \u00bb) totalement autonome.<\/li>\n\n\n\n<li><strong>La victoire d&rsquo;Axel Kicillof dans la province de Buenos Aires en septembre est principalement due aux dommages auto-inflig\u00e9s par le gouvernement de Javier Milei.<\/strong>&nbsp;Les 13 points d&rsquo;\u00e9cart en faveur de sa liste s&rsquo;expliquent par le fait qu&rsquo;une grande partie de l&rsquo;\u00e9lectorat pro-Milei \u00e9tait d\u00e9moralis\u00e9e par la situation \u00e9conomique difficile et les scandales de corruption pr\u00e9sum\u00e9e, et n&rsquo;est donc pas all\u00e9e voter (l&rsquo;affaire de l&rsquo;Agence nationale pour les personnes handicap\u00e9es et les enregistrements audio faisant r\u00e9f\u00e9rence \u00e0 la fameuse commission de 3 % vers\u00e9e \u00e0 la s\u0153ur de Milei, qui a \u00e9clat\u00e9 en ao\u00fbt).<\/li>\n\n\n\n<li>Le discours du pr\u00e9sident Milei apr\u00e8s sa victoire \u00e9tait tr\u00e8s intelligent : bien qu&rsquo;\u00e9videmment festif, il s&rsquo;est montr\u00e9 mesur\u00e9 et a appel\u00e9 les forces provinciales qui seront repr\u00e9sent\u00e9es au Congr\u00e8s national \u00e0 travailler ensemble pour des r\u00e9formes de \u00ab normalisation capitaliste \u00bb. La mani\u00e8re dont ce processus sera men\u00e9 est cruciale. <strong>Si le pr\u00e9sident Milei et son \u00e9quipe pensent pouvoir continuer sans affiner leurs m\u00e9canismes de direction politique et que les conditions \u00e9conomiques de leur \u00e9lectorat ne s&rsquo;am\u00e9liorent pas, ils subiront des revers encore plus importants dans l&rsquo;opinion publique que ceux qu&rsquo;ils ont connus en 2024, car ceux-ci s&rsquo;ajouteront aux pr\u00e9c\u00e9dents.<\/strong>&nbsp;La Libertad Avanza ne sortira pas indemne de ses scandales : les accusations de corruption concernant l&rsquo;Agence nationale pour les personnes handicap\u00e9es ou la r\u00e9v\u00e9lation du financement d&rsquo;un narcotrafiquant \u00e0 Jos\u00e9 Luis Espert, candidat mile\u00efste qui a d\u00fb renoncer \u00e0 sa candidature (dont l&rsquo;effet \u00e9lectoral a \u00e9t\u00e9 nul pour l&rsquo;instant). Tout cela g\u00e9n\u00e8re ce que nous appelons des \u00ab dommages cach\u00e9s \u00bb. Le gouvernement actuel accumule syst\u00e9matiquement des \u00ab dommages cach\u00e9s \u00bb. Il a d\u00e9j\u00e0 commenc\u00e9 \u00e0 en payer le prix dans l&rsquo;opinion publique, car son image a beaucoup souffert. Le plus int\u00e9ressant, c&rsquo;est que tous ces dommages sont auto-inflig\u00e9s.&nbsp;<strong>Il n&rsquo;a pas pay\u00e9 le prix fort en termes \u00e9lectoraux (mais il l&rsquo;a pay\u00e9, comme nous le verrons plus loin). Cela en dit long sur les probl\u00e8mes de direction politique au sein de Libertad Avanza et sur l&rsquo;incapacit\u00e9 d&rsquo;une opposition dispers\u00e9e et ennuyeuse.&nbsp;<\/strong>Le soutien de Trump \u00e0 l&rsquo;\u00e9conomie et \u00e0 la politique argentines ne sera pas non plus gratuit en termes d&rsquo;opinion publique, car il n&rsquo;est pas agr\u00e9able pour l&rsquo;estime de soi des citoyens.<\/li>\n\n\n\n<li><strong>Les sondages quantitatifs ne se sont PAS tromp\u00e9s, simplement une partie des ind\u00e9cis se sont tourn\u00e9s vers Libertad Avanza au cours de la derni\u00e8re semaine par crainte du chaos qui pourrait \u00e9clater si Libertad Avanza ne gagnait pas. Beaucoup d&rsquo;entre eux sont des \u00e9lecteurs de Milei d\u00e9\u00e7us par son gouvernement, car ils constatent une \u00e9norme baisse de leur pouvoir d&rsquo;achat.<\/strong>&nbsp;Ces ind\u00e9cis ont craint que l&rsquo;Argentine ne connaisse un effondrement \u00e9conomique le lundi suivant les \u00e9lections et ont d\u00e9cid\u00e9 de soutenir le gouvernement afin de pr\u00e9server la stabilit\u00e9 pr\u00e9caire du pays, maintenue gr\u00e2ce \u00e0 l&rsquo;aide de Donald Trump et du Tr\u00e9sor am\u00e9ricain. Pour la majorit\u00e9 du pays, la situation est d\u00e9j\u00e0 tr\u00e8s pesante : quelque chose de pire aurait \u00e9t\u00e9 insupportable.<\/li>\n\n\n\n<li>En termes absolus,&nbsp;<strong>par rapport aux \u00e9lections g\u00e9n\u00e9rales de 2023, le p\u00e9ronisme-kirchn\u00e9risme est pass\u00e9 de 9 200 000 voix \u00e0 7 200 000 : il a perdu 2 000 000 voix.<\/strong>&nbsp;Lors des \u00e9lections de mi-mandat de 2017 et \u00e9galement de 2021, il avait obtenu 7 900 000 voix. Autrement dit, entre ces \u00e9lections l\u00e9gislatives et celles-ci, le p\u00e9ronisme a perdu 700 000 voix.<\/li>\n\n\n\n<li>Milei devait absorber le macrisme (ce qui reste de la force de l&rsquo;ancien pr\u00e9sident Mauricio Macri) : lors des \u00e9lections g\u00e9n\u00e9rales de 2023, entre les deux (La Libertad Avanza d&rsquo;un c\u00f4t\u00e9, Juntos por el Cambio de l&rsquo;autre), ils totalisaient plus de 13 000 000 de voix. Cependant, lors des \u00e9lections g\u00e9n\u00e9rales de dimanche dernier, l&rsquo;alliance de Milei avec le macrisme a obtenu un peu plus de 9 000 000 de voix :&nbsp;<strong>la somme entre Milei et Macri a permis d&rsquo;obtenir 4 000 000 de voix en moins.&nbsp;<\/strong>Si j&rsquo;\u00e9tais membre de l&rsquo;\u00e9quipe de direction de La Libertad Avanza, je me pencherais sur cette question.<\/li>\n\n\n\n<li><strong>Lors des \u00e9lections g\u00e9n\u00e9rales de 2023, les votes blancs et nuls s&rsquo;\u00e9levaient \u00e0 3 000 000. Dimanche dernier, ils s&rsquo;\u00e9levaient \u00e0 1 200 000.&nbsp;<\/strong>Il y a donc eu 1 800 000 votes blancs et nuls en moins. Pourquoi cette baisse ?&nbsp;<strong>Le nombre d&rsquo;absents est pass\u00e9 de 8 000 000 \u00e0 11 000 000 au cours de la m\u00eame p\u00e9riode.&nbsp;<\/strong>Qui sont ces personnes ? Comment les classer ? Que pensent-elles ? Il serait prudent de les comprendre \u00e9galement.<\/li>\n\n\n\n<li>D&rsquo;un point de vue communicationnel, \u00e0 ce stade,&nbsp;<strong>Javier Milei n&rsquo;est plus un ph\u00e9nom\u00e8ne nouveau : rappelons-nous qu&rsquo;il s&rsquo;agit d&rsquo;une figure issue d&rsquo;un m\u00e9dia aussi ancien que la t\u00e9l\u00e9vision. Il a \u00e9t\u00e9 aid\u00e9 par des influenceurs importants, mais n&rsquo;a pratiquement pas cr\u00e9\u00e9 de contenu propre pour les r\u00e9seaux sociaux : contrairement \u00e0 ce que l&rsquo;on pourrait croire, son utilisation de TikTok \u00e9tait m\u00e9diocre. Le probl\u00e8me est que ce qui se trouve en face est trop vieux : cela n&rsquo;amuse personne.&nbsp;<\/strong>Et sans divertissement, il n&rsquo;y a pas d&rsquo;\u00e9motion et donc pas d&rsquo;information. Nous sommes en 2025, une ann\u00e9e marqu\u00e9e par des soul\u00e8vements politiques o\u00f9 les jeunes s&rsquo;organisent via Discord pour renverser les gouvernements. 2027 en Argentine sera une ann\u00e9e fructueuse pour les nouveaux entrepreneurs politiques, s&rsquo;il y en a.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Si pour des raisons professionnelles et\/ou personnelles, vous essayez de comprendre ce qui s&rsquo;est pass\u00e9 lors des \u00e9lections l\u00e9gislatives et parlementaires du dimanche 26 octobre, ceci peut vous aider. Si vous avez des commentaires, des questions ou des critiques, ils sont les bienvenus et vous pouvez les laisser ci-dessous, je vous r\u00e9pondrai tr\u00e8s certainement.<\/p>\n","protected":false},"author":103004725,"featured_media":1591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[121848],"tags":[],"class_list":["post-1592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorise"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9lections de mi-mandat 2025 : ce qui s&#039;est pass\u00e9 en Argentine - Lucas Malaspina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9lections de mi-mandat 2025 : ce qui s&#039;est pass\u00e9 en Argentine - Lucas Malaspina\" \/>\n<meta property=\"og:description\" content=\"Si pour des raisons professionnelles et\/ou personnelles, vous essayez de comprendre ce qui s&rsquo;est pass\u00e9 lors des \u00e9lections l\u00e9gislatives et parlementaires du dimanche 26 octobre, ceci peut vous aider. Si vous avez des commentaires, des questions ou des critiques, ils sont les bienvenus et vous pouvez les laisser ci-dessous, je vous r\u00e9pondrai tr\u00e8s certainement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucas Malaspina\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-10T13:57:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T14:27:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lucasmalaspina.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-29-a-las-16.20.37-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"lucasmalaspina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"lucasmalaspina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/\"},\"author\":{\"name\":\"lucasmalaspina\",\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/#\\\/schema\\\/person\\\/5a0f9f532b3275a2ec7efe26234f70c8\"},\"headline\":\"\u00c9lections de mi-mandat 2025 : ce qui s&rsquo;est pass\u00e9 en Argentine\",\"datePublished\":\"2025-11-10T13:57:31+00:00\",\"dateModified\":\"2025-11-10T14:27:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/\"},\"wordCount\":1428,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/lucasmalaspina.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Captura-de-pantalla-2025-10-29-a-las-16.20.37.png?fit=2264%2C1274&ssl=1\",\"articleSection\":[\"Non cat\u00e9goris\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/\",\"url\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/\",\"name\":\"\u00c9lections de mi-mandat 2025 : ce qui s'est pass\u00e9 en Argentine - Lucas Malaspina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/lucasmalaspina.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Captura-de-pantalla-2025-10-29-a-las-16.20.37.png?fit=2264%2C1274&ssl=1\",\"datePublished\":\"2025-11-10T13:57:31+00:00\",\"dateModified\":\"2025-11-10T14:27:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/lucasmalaspina.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Captura-de-pantalla-2025-10-29-a-las-16.20.37.png?fit=2264%2C1274&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/lucasmalaspina.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Captura-de-pantalla-2025-10-29-a-las-16.20.37.png?fit=2264%2C1274&ssl=1\",\"width\":2264,\"height\":1274},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/2025\\\/11\\\/10\\\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9lections de mi-mandat 2025 : ce qui s&#8217;est pass\u00e9 en Argentine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/\",\"name\":\"Lucas Malaspina\",\"description\":\"Communication politique et affaires publiques dans le chaos socio-num\u00e9rique\",\"publisher\":{\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/#organization\",\"name\":\"Lucas Malaspina\",\"url\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/lucasmalaspina.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/lucasmalaspina.jpeg?fit=225%2C225&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/lucasmalaspina.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/lucasmalaspina.jpeg?fit=225%2C225&ssl=1\",\"width\":225,\"height\":225,\"caption\":\"Lucas Malaspina\"},\"image\":{\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/#\\\/schema\\\/person\\\/5a0f9f532b3275a2ec7efe26234f70c8\",\"name\":\"lucasmalaspina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e68f3496168b30d970d12cc82cabbdf9c7715eeccec1ef6b9c24a51ef7de066a?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e68f3496168b30d970d12cc82cabbdf9c7715eeccec1ef6b9c24a51ef7de066a?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e68f3496168b30d970d12cc82cabbdf9c7715eeccec1ef6b9c24a51ef7de066a?s=96&d=identicon&r=g\",\"caption\":\"lucasmalaspina\"},\"sameAs\":[\"http:\\\/\\\/lucasmalaspina.com\"],\"url\":\"https:\\\/\\\/lucasmalaspina.com\\\/fr\\\/author\\\/lucmalaspina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9lections de mi-mandat 2025 : ce qui s'est pass\u00e9 en Argentine - Lucas Malaspina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9lections de mi-mandat 2025 : ce qui s'est pass\u00e9 en Argentine - Lucas Malaspina","og_description":"Si pour des raisons professionnelles et\/ou personnelles, vous essayez de comprendre ce qui s&rsquo;est pass\u00e9 lors des \u00e9lections l\u00e9gislatives et parlementaires du dimanche 26 octobre, ceci peut vous aider. Si vous avez des commentaires, des questions ou des critiques, ils sont les bienvenus et vous pouvez les laisser ci-dessous, je vous r\u00e9pondrai tr\u00e8s certainement.","og_url":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/","og_site_name":"Lucas Malaspina","article_published_time":"2025-11-10T13:57:31+00:00","article_modified_time":"2025-11-10T14:27:02+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/lucasmalaspina.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-29-a-las-16.20.37-1024x576.png","type":"image\/png"}],"author":"lucasmalaspina","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"lucasmalaspina","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/#article","isPartOf":{"@id":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/"},"author":{"name":"lucasmalaspina","@id":"https:\/\/lucasmalaspina.com\/fr\/#\/schema\/person\/5a0f9f532b3275a2ec7efe26234f70c8"},"headline":"\u00c9lections de mi-mandat 2025 : ce qui s&rsquo;est pass\u00e9 en Argentine","datePublished":"2025-11-10T13:57:31+00:00","dateModified":"2025-11-10T14:27:02+00:00","mainEntityOfPage":{"@id":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/"},"wordCount":1428,"commentCount":0,"publisher":{"@id":"https:\/\/lucasmalaspina.com\/fr\/#organization"},"image":{"@id":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/lucasmalaspina.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-29-a-las-16.20.37.png?fit=2264%2C1274&ssl=1","articleSection":["Non cat\u00e9goris\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/","url":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/","name":"\u00c9lections de mi-mandat 2025 : ce qui s'est pass\u00e9 en Argentine - Lucas Malaspina","isPartOf":{"@id":"https:\/\/lucasmalaspina.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/#primaryimage"},"image":{"@id":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/lucasmalaspina.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-29-a-las-16.20.37.png?fit=2264%2C1274&ssl=1","datePublished":"2025-11-10T13:57:31+00:00","dateModified":"2025-11-10T14:27:02+00:00","breadcrumb":{"@id":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/#primaryimage","url":"https:\/\/i0.wp.com\/lucasmalaspina.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-29-a-las-16.20.37.png?fit=2264%2C1274&ssl=1","contentUrl":"https:\/\/i0.wp.com\/lucasmalaspina.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-29-a-las-16.20.37.png?fit=2264%2C1274&ssl=1","width":2264,"height":1274},{"@type":"BreadcrumbList","@id":"https:\/\/lucasmalaspina.com\/fr\/2025\/11\/10\/milei-peronisme-elections-2025-ce-qui-sest-passe-en-argentine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lucasmalaspina.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9lections de mi-mandat 2025 : ce qui s&#8217;est pass\u00e9 en Argentine"}]},{"@type":"WebSite","@id":"https:\/\/lucasmalaspina.com\/fr\/#website","url":"https:\/\/lucasmalaspina.com\/fr\/","name":"Lucas Malaspina","description":"Communication politique et affaires publiques dans le chaos socio-num\u00e9rique","publisher":{"@id":"https:\/\/lucasmalaspina.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lucasmalaspina.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lucasmalaspina.com\/fr\/#organization","name":"Lucas Malaspina","url":"https:\/\/lucasmalaspina.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lucasmalaspina.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/lucasmalaspina.com\/wp-content\/uploads\/2024\/08\/lucasmalaspina.jpeg?fit=225%2C225&ssl=1","contentUrl":"https:\/\/i0.wp.com\/lucasmalaspina.com\/wp-content\/uploads\/2024\/08\/lucasmalaspina.jpeg?fit=225%2C225&ssl=1","width":225,"height":225,"caption":"Lucas Malaspina"},"image":{"@id":"https:\/\/lucasmalaspina.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lucasmalaspina.com\/fr\/#\/schema\/person\/5a0f9f532b3275a2ec7efe26234f70c8","name":"lucasmalaspina","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e68f3496168b30d970d12cc82cabbdf9c7715eeccec1ef6b9c24a51ef7de066a?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e68f3496168b30d970d12cc82cabbdf9c7715eeccec1ef6b9c24a51ef7de066a?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e68f3496168b30d970d12cc82cabbdf9c7715eeccec1ef6b9c24a51ef7de066a?s=96&d=identicon&r=g","caption":"lucasmalaspina"},"sameAs":["http:\/\/lucasmalaspina.com"],"url":"https:\/\/lucasmalaspina.com\/fr\/author\/lucmalaspina\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lucasmalaspina.com\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-29-a-las-16.20.37.png?fit=2264%2C1274&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg0sU9-pG","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/posts\/1592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/users\/103004725"}],"replies":[{"embeddable":true,"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/comments?post=1592"}],"version-history":[{"count":5,"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/posts\/1592\/revisions"}],"predecessor-version":[{"id":1604,"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/posts\/1592\/revisions\/1604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/media\/1591"}],"wp:attachment":[{"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/media?parent=1592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/categories?post=1592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lucasmalaspina.com\/fr\/wp-json\/wp\/v2\/tags?post=1592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}